{"id":1924,"date":"2025-12-11T14:20:19","date_gmt":"2025-12-11T05:20:19","guid":{"rendered":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288.jpg"},"modified":"2025-12-11T14:21:50","modified_gmt":"2025-12-11T05:21:50","slug":"egugz5nfcw11lz81765430288","status":"inherit","type":"attachment","link":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/2025\/12\/11\/%e7%ac%ac50%e5%9b%9e%e5%b1%b1%e6%a2%a8%e7%9c%8c%e5%ad%90%e3%81%a9%e3%82%82%e3%82%af%e3%83%a9%e3%83%96%e8%a6%aa%e7%9d%a6%e7%90%83%e6%8a%80%e5%a4%a7%e4%bc%9a%e3%80%80%e3%83%89%e3%83%83%e3%82%b8%e3%83%9c\/egugz5nfcw11lz81765430288\/","title":{"rendered":""},"author":57,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1924","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-300x200.jpg 300w, https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-768x512.jpg 768w, https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href=\"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/2025\/12\/11\/%e7%ac%ac50%e5%9b%9e%e5%b1%b1%e6%a2%a8%e7%9c%8c%e5%ad%90%e3%81%a9%e3%82%82%e3%82%af%e3%83%a9%e3%83%96%e8%a6%aa%e7%9d%a6%e7%90%83%e6%8a%80%e5%a4%a7%e4%bc%9a%e3%80%80%e3%83%89%e3%83%83%e3%82%b8%e3%83%9c\/egugz5nfcw11lz81765430288\/\" class=\"more\"><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":533,"file":"2025\/12\/EgugZ5nfCW11lZ81765430288.jpg","filesize":375339,"sizes":{"medium":{"file":"EgugZ5nfCW11lZ81765430288-300x200.jpg","width":300,"height":200,"filesize":18477,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-300x200.jpg"},"thumbnail":{"file":"EgugZ5nfCW11lZ81765430288-150x150.jpg","width":150,"height":150,"filesize":7791,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-150x150.jpg"},"medium_large":{"file":"EgugZ5nfCW11lZ81765430288-768x512.jpg","width":768,"height":512,"filesize":83326,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-768x512.jpg"},"post-thumbnail":{"file":"EgugZ5nfCW11lZ81765430288-550x280.jpg","width":550,"height":280,"filesize":40361,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-550x280.jpg"},"large-feature":{"file":"EgugZ5nfCW11lZ81765430288-550x280.jpg","width":550,"height":280,"filesize":40361,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288-550x280.jpg"},"full":{"file":"EgugZ5nfCW11lZ81765430288.jpg","width":800,"height":533,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon EOS R50","caption":"","created_timestamp":"1763894177","copyright":"","focal_length":"35","iso":"400","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]}},"post":1904,"source_url":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-content\/uploads\/sites\/46\/2025\/12\/EgugZ5nfCW11lZ81765430288.jpg","_links":{"self":[{"href":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-json\/wp\/v2\/media\/1924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kodomo-kai.or.jp\/yamanashi\/wp-json\/wp\/v2\/comments?post=1924"}]}}